{"id":1990,"date":"2026-07-15T11:18:21","date_gmt":"2026-07-15T14:18:21","guid":{"rendered":"https:\/\/www.officersoft.com.br\/site2020\/?post_type=artigo&#038;p=1990"},"modified":"2026-07-15T11:18:21","modified_gmt":"2026-07-15T14:18:21","slug":"customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft","status":"publish","type":"artigo","link":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/","title":{"rendered":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-1990","artigo","type-artigo","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Officer Soft - Solu\u00e7\u00f5es para Cart\u00f3rios\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T14:18:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T14:18:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/#listItem\",\"name\":\"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/#listItem\",\"position\":2,\"name\":\"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/#organization\",\"name\":\"Officer Soft\",\"description\":\"Solu\\u00e7\\u00f5es para Cart\\u00f3rios\",\"url\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/#webpage\",\"url\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/\",\"name\":\"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/artigo\\\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\\\/#breadcrumblist\"},\"datePublished\":\"2026-07-15T11:18:21-03:00\",\"dateModified\":\"2026-07-15T11:18:21-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/#website\",\"url\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/\",\"name\":\"Officer Soft\",\"description\":\"Solu\\u00e7\\u00f5es para Cart\\u00f3rios\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.officersoft.com.br\\\/site2020\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft","description":"","canonical_url":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.officersoft.com.br\/site2020#listItem","position":1,"name":"Home","item":"https:\/\/www.officersoft.com.br\/site2020","nextItem":{"@type":"ListItem","@id":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/#listItem","name":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft"}},{"@type":"ListItem","@id":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/#listItem","position":2,"name":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft","previousItem":{"@type":"ListItem","@id":"https:\/\/www.officersoft.com.br\/site2020#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.officersoft.com.br\/site2020\/#organization","name":"Officer Soft","description":"Solu\u00e7\u00f5es para Cart\u00f3rios","url":"https:\/\/www.officersoft.com.br\/site2020\/"},{"@type":"WebPage","@id":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/#webpage","url":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/","name":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.officersoft.com.br\/site2020\/#website"},"breadcrumb":{"@id":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/#breadcrumblist"},"datePublished":"2026-07-15T11:18:21-03:00","dateModified":"2026-07-15T11:18:21-03:00"},{"@type":"WebSite","@id":"https:\/\/www.officersoft.com.br\/site2020\/#website","url":"https:\/\/www.officersoft.com.br\/site2020\/","name":"Officer Soft","description":"Solu\u00e7\u00f5es para Cart\u00f3rios","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.officersoft.com.br\/site2020\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Officer Soft - Solu\u00e7\u00f5es para Cart\u00f3rios","og:type":"article","og:title":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft","og:url":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/","article:published_time":"2026-07-15T14:18:21+00:00","article:modified_time":"2026-07-15T14:18:21+00:00","twitter:card":"summary","twitter:title":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft - Officer Soft"},"aioseo_meta_data":{"post_id":"1990","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Customer centric no extrajudicial: como a OfficerSoft coloca o cliente no centro","score":30,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":[],"keyphraseLength":{"score":3,"maxScore":9,"error":1,"length":12},"keyphraseInURL":{"score":1,"maxScore":5,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 14:18:21","updated":"2026-07-15 14:52:57","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.officersoft.com.br\/site2020\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCustomer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.officersoft.com.br\/site2020"},{"label":"Customer centric no extrajudicial: como a proximidade com o cliente tem movido a OfficerSoft","link":"https:\/\/www.officersoft.com.br\/site2020\/artigo\/customer-centric-no-extrajudicial-como-a-proximidade-com-o-cliente-tem-movido-a-officersoft\/"}],"_links":{"self":[{"href":"https:\/\/www.officersoft.com.br\/site2020\/wp-json\/wp\/v2\/artigo\/1990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.officersoft.com.br\/site2020\/wp-json\/wp\/v2\/artigo"}],"about":[{"href":"https:\/\/www.officersoft.com.br\/site2020\/wp-json\/wp\/v2\/types\/artigo"}],"wp:attachment":[{"href":"https:\/\/www.officersoft.com.br\/site2020\/wp-json\/wp\/v2\/media?parent=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}